{"id":6564,"date":"2024-07-22T14:06:22","date_gmt":"2024-07-22T14:06:22","guid":{"rendered":"http:\/\/18.184.53.89\/?post_type=place&#038;p=6564"},"modified":"2025-07-30T10:01:35","modified_gmt":"2025-07-30T10:01:35","slug":"vipiteno-bressanone-mercatini-trentino","status":"publish","type":"place","link":"https:\/\/ae.r-owl.com\/index.php\/place\/vipiteno-bressanone-mercatini-trentino\/","title":{"rendered":"Mercatini di Natale a Vipiteno e Bressanone"},"content":{"rendered":"<p><strong>Mercatini di Natale a Vipiteno e Bressanone<\/strong><\/p>\n<p><strong>14 dicembre 2025<\/strong><\/p>\n<p><em><strong>Partenze: Cividate Camuno, Boario, Pisogne<\/strong><\/em><\/p>\n<p>Ritrovo dei partecipanti nel luogo e all\u2019orario convenuto e partenza in pullman Gran Turismo per Vipiteno. All\u2019arrivo tempo libero a disposizione per visitare i Mercatini di Natale. Cangianti ghirlande luminose, originali idee regalo e squisite prelibatezze per solleticare il palato. Il capoluogo dell&#8217;Alta Valle Isarco si trasforma in un&#8217;autentica fiaba invernale. Ai piedi della Torre delle Dodici, costruita nel 1486, artigiani locali mettono in vendita le loro opere, mentre le strade, le piazze e gli angoli di Vipiteno profumano di biscotti natalizi appena sfornati. Nel pomeriggio trasferimento a Bressanone. Ai piedi del magnifico Duomo si apre ai visitatori un mondo variopinto di profumi e sapori unici. Presepi realizzati a mano, sculture in legno, candele, oggetti di vetro e ceramica rallegrano gli occhi di chi guarda, mentre tipiche specialit\u00e0 della Valle Isarco allietano il palato di grandi e piccoli buongustai. Nel tardo pomeriggio partenza per il rientro in Valle con arrivo previsto in serata.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>La quota comprende<\/strong><\/p>\n<p><img decoding=\"async\" class=\"\" src=\"https:\/\/ae.r-owl.com\/wp-content\/uploads\/2022\/06\/check-inclusi.png\" width=\"22\" height=\"22\" \/> Viaggio A\/R in pullman Gran Turismo<\/p>\n<p>&nbsp;<\/p>\n<p><strong>La quota non comprende<\/strong><\/p>\n<p><img decoding=\"async\" class=\"\" src=\"https:\/\/ae.r-owl.com\/wp-content\/uploads\/2022\/06\/check-esclusi.png\" width=\"28\" height=\"28\" \/> Pasti<\/p>\n<p><img decoding=\"async\" class=\"\" src=\"https:\/\/ae.r-owl.com\/wp-content\/uploads\/2022\/06\/check-esclusi.png\" width=\"28\" height=\"28\" \/> Ingressi<\/p>\n<p><img decoding=\"async\" class=\"\" src=\"https:\/\/ae.r-owl.com\/wp-content\/uploads\/2022\/06\/check-esclusi.png\" width=\"28\" height=\"28\" \/> Visite guidate<\/p>\n<p><img decoding=\"async\" class=\"\" src=\"https:\/\/ae.r-owl.com\/wp-content\/uploads\/2022\/06\/check-esclusi.png\" width=\"28\" height=\"28\" \/> Extra di carattere personale e tutto quanto non espressamente indicato sotto la voce \u201cLa quota comprende\u201d<\/p>\n<p><a href=\"https:\/\/ae.r-owl.com\/index.php\/prodotto\/vipiteno-bressanone-mercatini-trentino\/\"><img decoding=\"async\" class=\"alignnone size-full wp-image-4984\" src=\"https:\/\/ae.r-owl.com\/wp-content\/uploads\/2022\/06\/btn-prenota-ora-green.png\" alt=\"\" width=\"175\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mercatini di Natale a Vipiteno e Bressanone 14 dicembre 2025 Partenze: Cividate Camuno, Boario, Pisogne Ritrovo dei partecipanti nel luogo e all\u2019orario convenuto e partenza in pullman Gran Turismo per Vipiteno. All\u2019arrivo tempo libero a disposizione per visitare i Mercatini di Natale. Cangianti ghirlande luminose, originali idee regalo e squisite prelibatezze per solleticare il palato. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6560,"menu_order":0,"template":"","place-type":[],"place-categories":[145],"place-amenities":[],"place-city":[256],"class_list":["post-6564","place","type-place","status-publish","has-post-thumbnail","hentry","place-categories-gite-in-giornata","place-city-bressanone"],"featured_media_url":"https:\/\/ae.r-owl.com\/wp-content\/uploads\/2024\/07\/vipiteno-bressanone-mercatini-natale-trentino-2.webp","golo-place_price_short":"55","golo-place_price_unit":"","golo-place_price_range":"0","golo-place_booking_type":"contact","golo-place_booking":"","golo-place_booking_site":"","golo-place_booking_2":"","golo-place_booking_site_2":"","golo-place_booking_banner":{"id":"0","url":""},"golo-place_booking_banner_url":"","golo-place_booking_form":"16","golo-booking_form_title":"","golo-booking_form_description":"","golo-booking_form_image":"","golo-place_phone":"+39 0364 535910","golo-place_phone2":"","golo-place_email":"info@adamelloexpress.com","golo-place_website":"","golo-place_identity":"7548","golo-google_review_placeid":"","golo-place_facebook":"","golo-place_instagram":"","golo-place_twitter":"","golo-additional_detail":"1","golo-additional_detail_icon":[""],"golo-additional_detail_name":[""],"golo-additional_detail_url":[""],"golo-opening_monday":"","golo-opening_monday_time":"","golo-monday_allday":"","golo-opening_tuesday":"","golo-opening_tuesday_time":"","golo-tuesday_allday":"","golo-opening_wednesday":"","golo-opening_wednesday_time":"","golo-wednesday_allday":"","golo-opening_thursday":"","golo-opening_thursday_time":"","golo-thursday_allday":"","golo-opening_friday":"","golo-opening_friday_time":"","golo-friday_allday":"","golo-opening_saturday":"","golo-opening_saturday_time":"","golo-saturday_allday":"","golo-opening_sunday":"","golo-opening_sunday_time":"","golo-sunday_allday":"","golo-yelp_review":"1","golo-yelp_review_title":["Hotel"],"golo-yelp_review_type":["hotel"],"golo-place_views_count":"7111","golo-date":"14 dicembre 2025","golo-menu_enable":"0","golo-menu_types":"1","golo-menu_types_name":[""],"golo-menu_tab":[{"golo-menu_title":"Viaggio A\/R in pullman Gran Turismo","golo-menu_price":"","golo-menu_description":"","golo-menu_image":{"id":"4956","url":"https:\/\/ae.r-owl.com\/wp-content\/uploads\/2022\/06\/check-inclusi.png"},"golo-menu_item_type":""},{"golo-menu_title":"Sistemazione in hotel 3* in camere doppie con servizi privati ","golo-menu_price":"","golo-menu_description":"","golo-menu_image":{"id":"4956","url":"https:\/\/ae.r-owl.com\/wp-content\/uploads\/2022\/06\/check-inclusi.png"},"golo-menu_item_type":""},{"golo-menu_title":"Tassa di soggiorno","golo-menu_price":"","golo-menu_description":"","golo-menu_image":{"id":"4957","url":"https:\/\/ae.r-owl.com\/wp-content\/uploads\/2022\/06\/check-esclusi.png"},"golo-menu_item_type":""},{"golo-menu_title":"Ingressi ai musei","golo-menu_price":"","golo-menu_description":"","golo-menu_image":{"id":"4957","url":"https:\/\/ae.r-owl.com\/wp-content\/uploads\/2022\/06\/check-esclusi.png"},"golo-menu_item_type":""},{"golo-menu_title":"Assicurazione annullamento al viaggio","golo-menu_price":"","golo-menu_description":"","golo-menu_image":{"id":"4957","url":"https:\/\/ae.r-owl.com\/wp-content\/uploads\/2022\/06\/check-esclusi.png"},"golo-menu_item_type":""},{"golo-menu_title":"Mance","golo-menu_price":"","golo-menu_description":"","golo-menu_image":{"id":"4957","url":"https:\/\/ae.r-owl.com\/wp-content\/uploads\/2022\/06\/check-esclusi.png"},"golo-menu_item_type":""}],"golo-place_address":"Bressanone","golo-place_zip":"","golo-place_timezone":"UTC+0","golo-place_location":{"location":"46.7104236,11.6524696","address":"39042 Bressanone BZ, Italia"},"golo-place_featured":"0","golo-place_logged":"0","golo-place_images":["https:\/\/ae.r-owl.com\/wp-content\/uploads\/2024\/07\/vipiteno-bressanone-mercatini-natale-trentino-2.webp","https:\/\/ae.r-owl.com\/wp-content\/uploads\/2024\/07\/vipiteno-bressanone-mercatini-natale-trentino-1.webp","https:\/\/ae.r-owl.com\/wp-content\/uploads\/2024\/07\/vipiteno-bressanone-mercatini-natale-trentino-3.jpg","https:\/\/ae.r-owl.com\/wp-content\/uploads\/2024\/07\/vipiteno-bressanone-mercatini-natale-trentino-2.jpg","https:\/\/ae.r-owl.com\/wp-content\/uploads\/2024\/07\/vipiteno-bressanone-mercatini-natale-trentino-1.jpg","https:\/\/ae.r-owl.com\/wp-content\/uploads\/2024\/07\/vipiteno-bressanone-mercatini-natale-trentino-4.jpg"],"golo-place_video_url":"","golo-place_video_image":"","golo-faqs_enable":"1","golo-faqs_tab":[{"golo-faqs_title":"Entro quanti giorni devo dare conferma?","golo-faqs_description":"Non c'\u00e8 un termine, va ad esaurimento posti"},{"golo-faqs_title":"Quanto pagano i bambini?","golo-faqs_description":"La tariffa \u00e8 uguale per tutti"},{"golo-faqs_title":"Bisogna pagare un acconto in fase di prenotazione?","golo-faqs_description":"\u00c8 richiesto il pagamento totale della gita"},{"golo-faqs_title":"A che ora si parte?","golo-faqs_description":"Per l'orario di partenza contattare l'agenzia 4\/5 giorni prima della gita"}],"golo-booking_item_name":"","golo-booking_item_id":"","golo-booking_item_author":"","golo-booking_adults":"","golo-booking_childrens":"","golo-booking_date":"","golo-booking_time":"","golo-place_coupon":"","golo-package_free":"","golo-package_price":"","golo-package_unlimited_time":"","golo-package_time_unit":"","golo-package_period":"","golo-package_unlimited_listing":"","golo-package_number_listings":"","golo-package_number_featured":"","golo-package_order_display":"","golo-package_featured":"","golo-package_visible":"","golo-package_extra_featured":"","golo-email_template_framework_type":"","golo-place_rating":"","golo-review_count":0,"_links":{"self":[{"href":"https:\/\/ae.r-owl.com\/index.php\/wp-json\/wp\/v2\/place\/6564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ae.r-owl.com\/index.php\/wp-json\/wp\/v2\/place"}],"about":[{"href":"https:\/\/ae.r-owl.com\/index.php\/wp-json\/wp\/v2\/types\/place"}],"author":[{"embeddable":true,"href":"https:\/\/ae.r-owl.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":2,"href":"https:\/\/ae.r-owl.com\/index.php\/wp-json\/wp\/v2\/place\/6564\/revisions"}],"predecessor-version":[{"id":7548,"href":"https:\/\/ae.r-owl.com\/index.php\/wp-json\/wp\/v2\/place\/6564\/revisions\/7548"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ae.r-owl.com\/index.php\/wp-json\/wp\/v2\/media\/6560"}],"wp:attachment":[{"href":"https:\/\/ae.r-owl.com\/index.php\/wp-json\/wp\/v2\/media?parent=6564"}],"wp:term":[{"taxonomy":"place-type","embeddable":true,"href":"https:\/\/ae.r-owl.com\/index.php\/wp-json\/wp\/v2\/place-type?post=6564"},{"taxonomy":"place-categories","embeddable":true,"href":"https:\/\/ae.r-owl.com\/index.php\/wp-json\/wp\/v2\/place-categories?post=6564"},{"taxonomy":"place-amenities","embeddable":true,"href":"https:\/\/ae.r-owl.com\/index.php\/wp-json\/wp\/v2\/place-amenities?post=6564"},{"taxonomy":"place-city","embeddable":true,"href":"https:\/\/ae.r-owl.com\/index.php\/wp-json\/wp\/v2\/place-city?post=6564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}