{"id":7513,"date":"2025-07-29T09:26:16","date_gmt":"2025-07-29T09:26:16","guid":{"rendered":"https:\/\/www.adamelloexpress.com\/?post_type=place&#038;p=7513"},"modified":"2025-07-29T16:57:42","modified_gmt":"2025-07-29T16:57:42","slug":"artigiano-in-fiera-10-dicembre","status":"publish","type":"place","link":"https:\/\/ae.r-owl.com\/index.php\/place\/artigiano-in-fiera-10-dicembre\/","title":{"rendered":"Artigiano in Fiera"},"content":{"rendered":"<p><strong>Artigiano in Fiera a Milano<\/strong><\/p>\n<p><strong>10 dicembre 2025<\/strong><\/p>\n<p><em><strong>Partenze: Cividate Camuno, Boario, Costa Volpino<\/strong><\/em><\/p>\n<p>Ritrovo dei partecipanti nel luogo e all\u2019orario convenuto e partenza in pullman Gran Turismo per Milano. Ingresso (gratuito) all\u2019Artigiano in Fiera. Alle 17:00 circa partenza per il rientro in Valle.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>La quota comprende<\/strong><\/p>\n<p><img decoding=\"async\" class=\"\" src=\"https:\/\/ae.r-owl.com\/wp-content\/uploads\/2022\/06\/check-inclusi.png\" width=\"22\" height=\"22\" \/> Viaggio A\/R in pullman Gran Turismo<\/p>\n<p>&nbsp;<\/p>\n<p><strong>La quota non comprende<\/strong><\/p>\n<p><img decoding=\"async\" class=\"\" src=\"https:\/\/ae.r-owl.com\/wp-content\/uploads\/2022\/06\/check-esclusi.png\" width=\"28\" height=\"28\" \/> Pasti<\/p>\n<p><img decoding=\"async\" class=\"\" src=\"https:\/\/ae.r-owl.com\/wp-content\/uploads\/2022\/06\/check-esclusi.png\" width=\"28\" height=\"28\" \/> Ingressi<\/p>\n<p><img decoding=\"async\" class=\"\" src=\"https:\/\/ae.r-owl.com\/wp-content\/uploads\/2022\/06\/check-esclusi.png\" width=\"28\" height=\"28\" \/> Visite guidate<\/p>\n<p><img decoding=\"async\" class=\"\" src=\"https:\/\/ae.r-owl.com\/wp-content\/uploads\/2022\/06\/check-esclusi.png\" width=\"28\" height=\"28\" \/> Extra di carattere personale e tutto quanto non espressamente indicato sotto la voce \u201cLa quota comprende\u201d<\/p>\n<p><a href=\"https:\/\/ae.r-owl.com\/index.php\/prodotto\/artigiano-in-fiera-10-dicembre\/\"><img decoding=\"async\" class=\"alignnone size-full wp-image-4984\" src=\"https:\/\/ae.r-owl.com\/wp-content\/uploads\/2022\/06\/btn-prenota-ora-green.png\" alt=\"\" width=\"175\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Artigiano in Fiera a Milano 10 dicembre 2025 Partenze: Cividate Camuno, Boario, Costa Volpino Ritrovo dei partecipanti nel luogo e all\u2019orario convenuto e partenza in pullman Gran Turismo per Milano. Ingresso (gratuito) all\u2019Artigiano in Fiera. Alle 17:00 circa partenza per il rientro in Valle. &nbsp; La quota comprende Viaggio A\/R in pullman Gran Turismo &nbsp; [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6516,"menu_order":0,"template":"","place-type":[],"place-categories":[145],"place-amenities":[],"place-city":[253],"class_list":["post-7513","place","type-place","status-publish","has-post-thumbnail","hentry","place-categories-gite-in-giornata","place-city-fiera-milano"],"featured_media_url":"https:\/\/ae.r-owl.com\/wp-content\/uploads\/2024\/07\/artigiano-in-fiera-milano-1.jpg","golo-place_price_short":"29","golo-place_price_unit":"","golo-place_price_range":"0","golo-place_booking_type":"contact","golo-place_booking":"","golo-place_booking_site":"","golo-place_booking_2":"","golo-place_booking_site_2":"","golo-place_booking_banner":{"id":"0","url":""},"golo-place_booking_banner_url":"","golo-place_booking_form":"16","golo-booking_form_title":"","golo-booking_form_description":"","golo-booking_form_image":"","golo-place_phone":"+39 0364 535910","golo-place_phone2":"","golo-place_email":"info@adamelloexpress.com","golo-place_website":"","golo-place_identity":"7514","golo-google_review_placeid":"","golo-place_facebook":"","golo-place_instagram":"","golo-place_twitter":"","golo-additional_detail":"1","golo-additional_detail_icon":[""],"golo-additional_detail_name":[""],"golo-additional_detail_url":[""],"golo-opening_monday":"","golo-opening_monday_time":"","golo-monday_allday":"","golo-opening_tuesday":"","golo-opening_tuesday_time":"","golo-tuesday_allday":"","golo-opening_wednesday":"","golo-opening_wednesday_time":"","golo-wednesday_allday":"","golo-opening_thursday":"","golo-opening_thursday_time":"","golo-thursday_allday":"","golo-opening_friday":"","golo-opening_friday_time":"","golo-friday_allday":"","golo-opening_saturday":"","golo-opening_saturday_time":"","golo-saturday_allday":"","golo-opening_sunday":"","golo-opening_sunday_time":"","golo-sunday_allday":"","golo-yelp_review":"1","golo-yelp_review_title":["Hotel"],"golo-yelp_review_type":["hotel"],"golo-place_views_count":"7535","golo-date":"10 dicembre 2025","golo-menu_enable":"0","golo-menu_types":"1","golo-menu_types_name":[""],"golo-menu_tab":[{"golo-menu_title":"Viaggio A\/R in pullman Gran Turismo","golo-menu_price":"","golo-menu_description":"","golo-menu_image":{"id":"4956","url":"https:\/\/ae.r-owl.com\/wp-content\/uploads\/2022\/06\/check-inclusi.png"},"golo-menu_item_type":""},{"golo-menu_title":"Sistemazione in hotel 3* in camere doppie con servizi privati ","golo-menu_price":"","golo-menu_description":"","golo-menu_image":{"id":"4956","url":"https:\/\/ae.r-owl.com\/wp-content\/uploads\/2022\/06\/check-inclusi.png"},"golo-menu_item_type":""},{"golo-menu_title":"Tassa di soggiorno","golo-menu_price":"","golo-menu_description":"","golo-menu_image":{"id":"4957","url":"https:\/\/ae.r-owl.com\/wp-content\/uploads\/2022\/06\/check-esclusi.png"},"golo-menu_item_type":""},{"golo-menu_title":"Ingressi ai musei","golo-menu_price":"","golo-menu_description":"","golo-menu_image":{"id":"4957","url":"https:\/\/ae.r-owl.com\/wp-content\/uploads\/2022\/06\/check-esclusi.png"},"golo-menu_item_type":""},{"golo-menu_title":"Assicurazione annullamento al viaggio","golo-menu_price":"","golo-menu_description":"","golo-menu_image":{"id":"4957","url":"https:\/\/ae.r-owl.com\/wp-content\/uploads\/2022\/06\/check-esclusi.png"},"golo-menu_item_type":""},{"golo-menu_title":"Mance","golo-menu_price":"","golo-menu_description":"","golo-menu_image":{"id":"4957","url":"https:\/\/ae.r-owl.com\/wp-content\/uploads\/2022\/06\/check-esclusi.png"},"golo-menu_item_type":""}],"golo-place_address":"Fiera Milano","golo-place_zip":"","golo-place_timezone":"UTC+0","golo-place_location":{"location":"45.5189442,9.0856652","address":"Largo Metropolitana, 5, 20017 Rho MI, Italia"},"golo-place_featured":"0","golo-place_logged":"0","golo-place_images":["https:\/\/ae.r-owl.com\/wp-content\/uploads\/2024\/07\/artigiano-in-fiera-milano-1.jpg","https:\/\/ae.r-owl.com\/wp-content\/uploads\/2024\/07\/artigiano-in-fiera-milano-5.webp","https:\/\/ae.r-owl.com\/wp-content\/uploads\/2024\/07\/artigiano-in-fiera-milano-4.jpg","https:\/\/ae.r-owl.com\/wp-content\/uploads\/2024\/07\/artigiano-in-fiera-milano-2.jpg","https:\/\/ae.r-owl.com\/wp-content\/uploads\/2024\/07\/artigiano-in-fiera-milano-3.jpg"],"golo-place_video_url":"","golo-place_video_image":"","golo-faqs_enable":"1","golo-faqs_tab":[{"golo-faqs_title":"Entro quanti giorni devo dare conferma?","golo-faqs_description":"Non c'\u00e8 un termine, va ad esaurimento posti"},{"golo-faqs_title":"Quanto pagano i bambini?","golo-faqs_description":"La tariffa \u00e8 uguale per tutti"},{"golo-faqs_title":"Bisogna pagare un acconto in fase di prenotazione?","golo-faqs_description":"\u00c8 richiesto il pagamento totale della gita"},{"golo-faqs_title":"A che ora si parte?","golo-faqs_description":"Per l'orario di partenza contattare l'agenzia 4\/5 giorni prima della gita"}],"golo-booking_item_name":"","golo-booking_item_id":"","golo-booking_item_author":"","golo-booking_adults":"","golo-booking_childrens":"","golo-booking_date":"","golo-booking_time":"","golo-place_coupon":"","golo-package_free":"","golo-package_price":"","golo-package_unlimited_time":"","golo-package_time_unit":"","golo-package_period":"","golo-package_unlimited_listing":"","golo-package_number_listings":"","golo-package_number_featured":"","golo-package_order_display":"","golo-package_featured":"","golo-package_visible":"","golo-package_extra_featured":"","golo-email_template_framework_type":"","golo-place_rating":"","golo-review_count":0,"_links":{"self":[{"href":"https:\/\/ae.r-owl.com\/index.php\/wp-json\/wp\/v2\/place\/7513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ae.r-owl.com\/index.php\/wp-json\/wp\/v2\/place"}],"about":[{"href":"https:\/\/ae.r-owl.com\/index.php\/wp-json\/wp\/v2\/types\/place"}],"author":[{"embeddable":true,"href":"https:\/\/ae.r-owl.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":1,"href":"https:\/\/ae.r-owl.com\/index.php\/wp-json\/wp\/v2\/place\/7513\/revisions"}],"predecessor-version":[{"id":7514,"href":"https:\/\/ae.r-owl.com\/index.php\/wp-json\/wp\/v2\/place\/7513\/revisions\/7514"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ae.r-owl.com\/index.php\/wp-json\/wp\/v2\/media\/6516"}],"wp:attachment":[{"href":"https:\/\/ae.r-owl.com\/index.php\/wp-json\/wp\/v2\/media?parent=7513"}],"wp:term":[{"taxonomy":"place-type","embeddable":true,"href":"https:\/\/ae.r-owl.com\/index.php\/wp-json\/wp\/v2\/place-type?post=7513"},{"taxonomy":"place-categories","embeddable":true,"href":"https:\/\/ae.r-owl.com\/index.php\/wp-json\/wp\/v2\/place-categories?post=7513"},{"taxonomy":"place-amenities","embeddable":true,"href":"https:\/\/ae.r-owl.com\/index.php\/wp-json\/wp\/v2\/place-amenities?post=7513"},{"taxonomy":"place-city","embeddable":true,"href":"https:\/\/ae.r-owl.com\/index.php\/wp-json\/wp\/v2\/place-city?post=7513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}